{"id":14648,"date":"2023-03-17T19:34:02","date_gmt":"2023-03-17T19:34:02","guid":{"rendered":"https:\/\/www.aldevaldesign.com\/?post_type=work&#038;p=14648"},"modified":"2023-05-18T20:30:19","modified_gmt":"2023-05-18T20:30:19","slug":"renders","status":"publish","type":"work","link":"https:\/\/www.aldevaldesign.com\/es\/work\/renders\/","title":{"rendered":"Renders"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"14648\" class=\"elementor elementor-14648\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-429cc10 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"429cc10\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-6502077\" data-id=\"6502077\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5883f8f elementor-widget elementor-widget-image-carousel\" data-id=\"5883f8f\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;pause_on_hover&quot;:&quot;no&quot;,&quot;pause_on_interaction&quot;:&quot;no&quot;,&quot;autoplay_speed&quot;:100,&quot;effect&quot;:&quot;fade&quot;,&quot;speed&quot;:5000,&quot;autoplay&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.0 - 13-02-2023 *\/\n.elementor-widget-image-carousel .swiper,.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure,.elementor-widget-image-carousel .swiper .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized) .swiper-slide,.elementor-image-carousel-wrapper:not(.swiper-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Exterior-Final-min.jpg\" alt=\"Renders\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Lobby-7mo-piso-min.jpg\" alt=\"Renders\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Waiting-Area-min.jpg\" alt=\"Renders\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2803257\" data-id=\"2803257\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1705c60 elementor-widget elementor-widget-image\" data-id=\"1705c60\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.0 - 13-02-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/5th-floor-min-1300x731.jpg\" class=\"attachment-large size-large wp-image-14656\" alt=\"\" srcset=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/5th-floor-min-1300x731.jpg 1300w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/5th-floor-min-400x225.jpg 400w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/5th-floor-min-768x432.jpg 768w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/5th-floor-min-1536x864.jpg 1536w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/5th-floor-min-18x10.jpg 18w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/5th-floor-min.jpg 2000w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-671420b elementor-widget elementor-widget-image\" data-id=\"671420b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/7th-floor-min-1300x731.jpg\" class=\"attachment-large size-large wp-image-14652\" alt=\"\" srcset=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/7th-floor-min-1300x731.jpg 1300w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/7th-floor-min-400x225.jpg 400w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/7th-floor-min-768x432.jpg 768w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/7th-floor-min-1536x864.jpg 1536w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/7th-floor-min-18x10.jpg 18w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/7th-floor-min.jpg 2000w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-0e41960\" data-id=\"0e41960\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58818c7 elementor-widget elementor-widget-image\" data-id=\"58818c7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Fifth-Floor-Rendering-min-1300x731.jpg\" class=\"attachment-large size-large wp-image-14655\" alt=\"\" srcset=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Fifth-Floor-Rendering-min-1300x731.jpg 1300w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Fifth-Floor-Rendering-min-400x225.jpg 400w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Fifth-Floor-Rendering-min-768x432.jpg 768w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Fifth-Floor-Rendering-min-18x10.jpg 18w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Fifth-Floor-Rendering-min.jpg 1500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09f39ab elementor-widget elementor-widget-image\" data-id=\"09f39ab\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Fifth-Floor-Rendering-min-1300x731.jpg\" class=\"attachment-large size-large wp-image-14655\" alt=\"\" srcset=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Fifth-Floor-Rendering-min-1300x731.jpg 1300w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Fifth-Floor-Rendering-min-400x225.jpg 400w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Fifth-Floor-Rendering-min-768x432.jpg 768w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Fifth-Floor-Rendering-min-18x10.jpg 18w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Fifth-Floor-Rendering-min.jpg 1500w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a07fe39 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a07fe39\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2008460\" data-id=\"2008460\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0e62e9 elementor-widget elementor-widget-image\" data-id=\"b0e62e9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Ed_final_3-9_009-min-1280x800.jpg\" class=\"attachment-large size-large wp-image-14663\" alt=\"\" srcset=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Ed_final_3-9_009-min-1280x800.jpg 1280w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Ed_final_3-9_009-min-400x250.jpg 400w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Ed_final_3-9_009-min-768x480.jpg 768w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Ed_final_3-9_009-min-1536x960.jpg 1536w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Ed_final_3-9_009-min-18x12.jpg 18w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Ed_final_3-9_009-min.jpg 1920w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f7276b elementor-widget elementor-widget-image\" data-id=\"5f7276b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Ed_final_3-9_007-min-1280x800.jpg\" class=\"attachment-large size-large wp-image-14666\" alt=\"\" srcset=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Ed_final_3-9_007-min-1280x800.jpg 1280w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Ed_final_3-9_007-min-400x250.jpg 400w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Ed_final_3-9_007-min-768x480.jpg 768w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Ed_final_3-9_007-min-1536x960.jpg 1536w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Ed_final_3-9_007-min-18x12.jpg 18w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Ed_final_3-9_007-min.jpg 1920w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-48048ea\" data-id=\"48048ea\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e762501 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e762501\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2af95a9\" data-id=\"2af95a9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9cdabf elementor-widget elementor-widget-image\" data-id=\"f9cdabf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Rendering-for-Sign-min-1300x732.jpg\" class=\"attachment-large size-large wp-image-14674\" alt=\"\" srcset=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Rendering-for-Sign-min-1300x732.jpg 1300w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Rendering-for-Sign-min-400x225.jpg 400w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Rendering-for-Sign-min-768x432.jpg 768w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Rendering-for-Sign-min-1536x864.jpg 1536w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Rendering-for-Sign-min-2048x1152.jpg 2048w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/Rendering-for-Sign-min-18x10.jpg 18w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5f80a9e\" data-id=\"5f80a9e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e7347e7 elementor-widget elementor-widget-image\" data-id=\"e7347e7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/0515-LSV-front-min-1300x731.jpg\" class=\"attachment-large size-large wp-image-14675\" alt=\"\" srcset=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/0515-LSV-front-min-1300x731.jpg 1300w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/0515-LSV-front-min-400x225.jpg 400w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/0515-LSV-front-min-768x432.jpg 768w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/0515-LSV-front-min-1536x864.jpg 1536w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/0515-LSV-front-min-2048x1152.jpg 2048w, https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/2023\/03\/0515-LSV-front-min-18x10.jpg 18w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-46b9ac3c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"46b9ac3c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-197a4482\" data-id=\"197a4482\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e8c22fa elementor-widget elementor-widget-heading\" data-id=\"5e8c22fa\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.0 - 13-02-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><div class=\"elementor-heading-title elementor-size-default\">\u00bfListo para comenzar un proyecto?<\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-20fc3411 elementor-widget elementor-widget-heading\" data-id=\"20fc3411\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<span class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/www.aldevaldesign.com\/es\/contact\/\">Trabaja con nosotros<\/a><\/span>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-47a6384 elementor-section-full_width elementor-section-stretched elementor-section-height-default elementor-section-height-default\" data-id=\"47a6384\" data-element_type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ea7968\" data-id=\"4ea7968\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5dbff2a elementor-widget elementor-widget-a13fe-post-list\" data-id=\"5dbff2a\" data-element_type=\"widget\" data-widget_type=\"a13fe-post-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"bricks-frame works-bricks works-bricks-1  variant-overlay works-columns-5 hover-effect-drop title-bottom title-left cover-no-hover cover-hover gradient-hover texts-no-hover texts-hover\">\n\t\t\t\t<div class=\"works-grid-container\" data-margin=\"5\">\n\t\t\t\t<div class=\"grid-master\"><\/div>\n\t\t\t\t<div class=\"archive-item object-item open-item-normal w1\" data-category-106=\"1\" data-id=\"work-12573\" itemtype=\"https:\/\/schema.org\/CreativeWork\" itemscope><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/apollo13_images\/PC100028-scaled-7csecelvyd0rtjlrjuetz3ab6xph37dih6.jpg\" alt=\"\" title=\"OLYMPUS DIGITAL CAMERA\" width=\"316\" height=\"316\" \/><div class=\"cover\" style=\"background-color:rgba(0,0,0, 0.7);\"><\/div><div class=\"covering-image\"><\/div><div class=\"icon a13icon-plus\"><\/div><div class=\"caption\"><div class=\"texts_group\"><h2 class=\"post-title\" itemprop=\"headline\">Eastern National Bank<\/h2><div class=\"excerpt\">Dise\u00f1o &amp; Desarrollo<\/div><\/div><\/div><a href=\"https:\/\/www.aldevaldesign.com\/es\/work\/enb\/\" itemprop=\"url\"><\/a><div class=\"social\"><\/div><\/div><div class=\"archive-item object-item open-item-normal w1\" data-category-103=\"1\" data-category-105=\"1\" data-id=\"work-14560\" itemtype=\"https:\/\/schema.org\/CreativeWork\" itemscope><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/apollo13_images\/WhatsApp-Image-2023-03-17-at-9.33.48-AM-2-1-7d36f7zd1kww659honi5n6kcsc3gi1zlqi.jpeg\" alt=\"\" title=\"Residential complex\" width=\"316\" height=\"316\" \/><div class=\"cover\" style=\"background-color:rgba(0,0,0, 0.7);\"><\/div><div class=\"covering-image\"><\/div><div class=\"icon a13icon-plus\"><\/div><div class=\"caption\"><div class=\"texts_group\"><h2 class=\"post-title\" itemprop=\"headline\">Residences<\/h2><div class=\"excerpt\">Dise\u00f1o &amp; Desarrollo<\/div><\/div><\/div><a href=\"https:\/\/www.aldevaldesign.com\/es\/work\/residential-complex\/\" itemprop=\"url\"><\/a><div class=\"social\"><\/div><\/div><div class=\"archive-item object-item open-item-normal w1\" data-category-106=\"1\" data-id=\"work-12601\" itemtype=\"https:\/\/schema.org\/CreativeWork\" itemscope><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/apollo13_images\/main-delco-7csf2jpi4mqjero2xhefyuwtt37s9wupqi.jpg\" alt=\"\" title=\"BMS CAT\" width=\"316\" height=\"316\" \/><div class=\"cover\" style=\"background-color:rgba(0,0,0, 0.7);\"><\/div><div class=\"covering-image\"><\/div><div class=\"icon a13icon-plus\"><\/div><div class=\"caption\"><div class=\"texts_group\"><h2 class=\"post-title\" itemprop=\"headline\">BMS CAT<\/h2><div class=\"excerpt\">Almacenes<\/div><\/div><\/div><a href=\"https:\/\/www.aldevaldesign.com\/es\/work\/warehouses\/\" itemprop=\"url\"><\/a><div class=\"social\"><\/div><\/div><div class=\"archive-item object-item open-item-normal w1\" data-category-105=\"1\" data-id=\"work-13047\" itemtype=\"https:\/\/schema.org\/CreativeWork\" itemscope><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/apollo13_images\/Alexander-June-2013-053-scaled-7csxxbfs88fhng3l3rfy1q37bk1g6l1ccq.jpg\" alt=\"\" title=\"Delgado Residence\" width=\"316\" height=\"316\" \/><div class=\"cover\" style=\"background-color:rgba(0,0,0, 0.7);\"><\/div><div class=\"covering-image\"><\/div><div class=\"icon a13icon-plus\"><\/div><div class=\"caption\"><div class=\"texts_group\"><h2 class=\"post-title\" itemprop=\"headline\">Delgado Residence<\/h2><div class=\"excerpt\">Residencia Completa<\/div><\/div><\/div><a href=\"https:\/\/www.aldevaldesign.com\/es\/work\/delgado-residence\/\" itemprop=\"url\"><\/a><div class=\"social\"><\/div><\/div><div class=\"archive-item object-item open-item-normal w1\" data-category-106=\"1\" data-category-107=\"1\" data-id=\"work-14648\" itemtype=\"https:\/\/schema.org\/CreativeWork\" itemscope><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.aldevaldesign.com\/wp-content\/uploads\/apollo13_images\/5th-floor-min-7d37i67w7fz3pbne1pm26iiuk9fh3njqve.jpg\" alt=\"\" title=\"Renders\" width=\"316\" height=\"316\" \/><div class=\"cover\" style=\"background-color:rgba(0,0,0, 0.7);\"><\/div><div class=\"covering-image\"><\/div><div class=\"icon a13icon-plus\"><\/div><div class=\"caption\"><div class=\"texts_group\"><h2 class=\"post-title\" itemprop=\"headline\">Renders<\/h2><div class=\"excerpt\">Dise\u00f1o &amp; Renders<\/div><\/div><\/div><a href=\"https:\/\/www.aldevaldesign.com\/es\/work\/renders\/\" itemprop=\"url\"><\/a><div class=\"social\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"clear\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Ready to start a project? Work with Us Architectural drawings Designs and Drawings Eastern National Bank Design and Development Eastern National Bank Brickell Headquarter Homestead Residences Design&hellip;<\/p>\n<p> <a class=\"more-link\" href=\"https:\/\/www.aldevaldesign.com\/es\/work\/renders\/\">Leer m\u00e1s<\/a><\/p>","protected":false},"featured_media":14656,"comment_status":"closed","ping_status":"closed","template":"","class_list":["post-14648","work","type-work","status-publish","has-post-thumbnail","work_genre-commercial","work_genre-industrial"],"_links":{"self":[{"href":"https:\/\/www.aldevaldesign.com\/es\/wp-json\/wp\/v2\/work\/14648","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.aldevaldesign.com\/es\/wp-json\/wp\/v2\/work"}],"about":[{"href":"https:\/\/www.aldevaldesign.com\/es\/wp-json\/wp\/v2\/types\/work"}],"replies":[{"embeddable":true,"href":"https:\/\/www.aldevaldesign.com\/es\/wp-json\/wp\/v2\/comments?post=14648"}],"version-history":[{"count":21,"href":"https:\/\/www.aldevaldesign.com\/es\/wp-json\/wp\/v2\/work\/14648\/revisions"}],"predecessor-version":[{"id":15451,"href":"https:\/\/www.aldevaldesign.com\/es\/wp-json\/wp\/v2\/work\/14648\/revisions\/15451"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.aldevaldesign.com\/es\/wp-json\/wp\/v2\/media\/14656"}],"wp:attachment":[{"href":"https:\/\/www.aldevaldesign.com\/es\/wp-json\/wp\/v2\/media?parent=14648"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}